{"id":1549,"date":"2023-09-29T17:09:51","date_gmt":"2023-09-29T15:09:51","guid":{"rendered":"https:\/\/solar.clubslab.com\/?page_id=1549"},"modified":"2023-10-15T20:48:50","modified_gmt":"2023-10-15T18:48:50","slug":"impressum","status":"publish","type":"page","link":"https:\/\/solarws.de\/index.php\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1549\" class=\"elementor elementor-1549\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b696339 e-flex e-con-boxed e-con e-parent\" data-id=\"b696339\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c220cf elementor-widget elementor-widget-text-editor\" data-id=\"6c220cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 20-09-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Anbieter<br \/>WS Projekt GmbH<br \/>Rheinalle 25 b<br \/>53173 Bonn<br \/>Handelsregister: Bonn, HRB 28019<br \/>Gesch\u00e4ftsf\u00fchrer\/MD: Weckbecker, Michael<br \/><b>Kontakt<\/b><br \/>Telefon: +49-(02 28)95 67 9-0<br \/>E-Mail: info(at)SolarWS.de<br \/>Verantwortlich f\u00fcr den Inhalt:<br \/>WS Projekt GmbH<br \/>Rheinalle 25 b<br \/>53173 Bonn<br \/>Handelsregister: Bonn, HRB 28019<br \/>Gesch\u00e4ftsf\u00fchrer\/MD: Weckbecker, Michael<br \/>Telefon: +49-(02 28)95 67 9-0<br \/>E-Mail: info(at)SolarWS.de<\/p><p>Haftungsausschluss:\u2028<br \/>Wir bem\u00fchen uns, dass die auf dieser Website enthaltenen Informationen und Daten zutreffend sind. Eine Haftung oder Garantie f\u00fcr die Aktualit\u00e4t, Richtigkeit und Vollst\u00e4ndigkeit der zur Verf\u00fcgung gestellten Informationen und Daten ist jedoch ausgeschlossen.<br \/>Als Diensteanbieter sind wir gem\u00e4\u00df \u00a7 7 Abs.1 TMG f\u00fcr eigene Inhalte auf diesen Seiten nach den allgemeinen Gesetzen verantwortlich. Nach \u00a7\u00a7 8 bis 10 TMG sind wir als Diensteanbieter jedoch nicht verpflichtet, \u00fcbermittelte oder gespeicherte fremde Informationen zu \u00fcberwachen oder nach Umst\u00e4nden zu forschen, die auf eine rechtswidrige T\u00e4tigkeit hinweisen.<br \/>Verpflichtungen zur Entfernung oder Sperrung der Nutzung von Informationen nach den allgemeinen Gesetzen bleiben hiervon unber\u00fchrt. Eine diesbez\u00fcgliche Haftung ist jedoch erst ab dem Zeitpunkt der Kenntnis einer konkreten Rechtsverletzung m\u00f6glich. Bei Bekanntwerden von entsprechenden Rechtsverletzungen werden wir diese Inhalte umgehend entfernen.Externe Links:\u2028<br \/>Unser Angebot enth\u00e4lt Links zu externen Websites Dritter, auf deren Inhalte wir keinen Einfluss haben. Deshalb k\u00f6nnen wir f\u00fcr diese fremden Inhalte auch keine Gew\u00e4hr \u00fcbernehmen. F\u00fcr die Inhalte der verlinkten Seiten ist stets der jeweilige Anbieter oder Betreiber der Seiten verantwortlich. Die verlinkten Seiten wurden zum Zeitpunkt der Verlinkung auf m\u00f6gliche Rechtsverst\u00f6\u00dfe \u00fcberpr\u00fcft. Rechtswidrige Inhalte waren zum Zeitpunkt der Verlinkung nicht erkennbar.<br \/>Eine permanente inhaltliche Kontrolle der verlinkten Seiten ist jedoch ohne konkrete Anhaltspunkte einer Rechtsverletzung nicht zumutbar. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Links umgehend entfernen.<br \/>Urheberrecht<br \/>Die durch die Seitenbetreiber erstellten Inhalte und Werke auf diesen Seiten unterliegen dem deutschen Urheberrecht. Die Vervielf\u00e4ltigung, Bearbeitung, Verbreitung und jede Art der Verwertung au\u00dferhalb der Grenzen des Urheberrechtes bed\u00fcrfen der schriftlichen Zustimmung des jeweiligen Autors bzw. Erstellers. Downloads und Kopien dieser Seite sind nur f\u00fcr den privaten, nicht kommerziellen Gebrauch gestattet.<br \/>Soweit die Inhalte auf dieser Seite nicht vom Betreiber erstellt wurden, werden die Urheberrechte Dritter beachtet. Insbesondere werden Inhalte Dritter als solche gekennzeichnet. Sollten Sie trotzdem auf eine Urheberrechtsverletzung aufmerksam werden, bitten wir um einen entsprechenden Hinweis. Bei Bekanntwerden von Rechtsverletzungen werden wir derartige Inhalte umgehend entfernen.<br \/>Streitbeilegung\u2028<br \/>Die Europ\u00e4ische Kommission stellt eine Plattform f\u00fcr die au\u00dfergerichtliche Online-Streitbeilegung (OS-Plattform) bereit, die unter\u00a0http:\/\/ec.europa.eu\/consumers\/odr\u00a0abrufbar ist. Unsere E-Mail-Adresse finden Sie im Impressum. Wir sind weder verpflichtet noch bereit, an dem Streitschlichtungsverfahren teilzunehmen.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>AnbieterWS Projekt GmbHRheinalle 25 b53173 BonnHandelsregister: Bonn, HRB 28019Gesch\u00e4ftsf\u00fchrer\/MD: Weckbecker, MichaelKontaktTelefon: +49-(02 28)95 67 9-0E-Mail: info(at)SolarWS.deVerantwortlich f\u00fcr den Inhalt:WS Projekt GmbHRheinalle 25 b53173 BonnHandelsregister: Bonn, HRB 28019Gesch\u00e4ftsf\u00fchrer\/MD: Weckbecker, MichaelTelefon: +49-(02 28)95 67 9-0E-Mail: info(at)SolarWS.de Haftungsausschluss:\u2028Wir bem\u00fchen uns, dass die auf dieser Website enthaltenen Informationen und Daten zutreffend sind. Eine Haftung oder Garantie f\u00fcr die Aktualit\u00e4t, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"blocksy_meta":"","aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/pages\/1549"}],"collection":[{"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/comments?post=1549"}],"version-history":[{"count":13,"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/pages\/1549\/revisions"}],"predecessor-version":[{"id":1630,"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/pages\/1549\/revisions\/1630"}],"wp:attachment":[{"href":"https:\/\/solarws.de\/index.php\/wp-json\/wp\/v2\/media?parent=1549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}